{"id":23004,"date":"2022-04-09T07:17:58","date_gmt":"2022-04-09T07:17:58","guid":{"rendered":"https:\/\/www.ergio.ro\/co\/portfolio\/eva-jordi\/"},"modified":"2022-04-09T07:17:58","modified_gmt":"2022-04-09T07:17:58","slug":"eva-jordi","status":"publish","type":"jetpack-portfolio","link":"https:\/\/www.ergio.ro\/co\/it\/portfolio\/eva-jordi\/","title":{"rendered":"Eva Jordi"},"content":{"rendered":"<p>Questo progetto si distingue nel design, perch\u00e9 ti fa pensare che sia una costruzione classica.<\/p>\n<p>L&#8217;estetica dell&#8217;intero edificio si fonde con il paesaggio e gli elementi ambientali, risultando in un&#8217;immagine armoniosa.<\/p>\n<p>Gli elementi sorprendenti sono il terrazzo e i tetti dritti con travi lamellari a vista, impregnati con una vernice ecologica all&#8217;acqua.<\/p>\n<h6>&nbsp;<\/h6>\n<h6>Superficie<\/h6>\n<p>146 m2<\/p>\n<h6>&nbsp;<\/h6>\n<h6>Posizione<\/h6>\n<p>Barcelona, Spagna<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questo progetto si distingue nel design, perch\u00e9 ti fa pensare che sia una costruzione classica. L&#8217;estetica dell&#8217;intero edificio si fonde con il paesaggio e gli elementi ambientali, risultando in un&#8217;immagine armoniosa. Gli elementi sorprendenti sono il terrazzo e i tetti dritti con travi lamellari a vista, impregnati con una vernice ecologica all&#8217;acqua. &nbsp; Superficie 146 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15509,"comment_status":"open","ping_status":"closed","template":"","jetpack-portfolio-type":[173,174],"jetpack-portfolio-tag":[],"class_list":["post-23004","jetpack-portfolio","type-jetpack-portfolio","status-publish","has-post-thumbnail","hentry","jetpack-portfolio-type-telaio-in-legno","jetpack-portfolio-type-tetto-a-terrazza"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ergio.ro\/co\/it\/wp-json\/wp\/v2\/jetpack-portfolio\/23004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ergio.ro\/co\/it\/wp-json\/wp\/v2\/jetpack-portfolio"}],"about":[{"href":"https:\/\/www.ergio.ro\/co\/it\/wp-json\/wp\/v2\/types\/jetpack-portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.ergio.ro\/co\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ergio.ro\/co\/it\/wp-json\/wp\/v2\/comments?post=23004"}],"version-history":[{"count":0,"href":"https:\/\/www.ergio.ro\/co\/it\/wp-json\/wp\/v2\/jetpack-portfolio\/23004\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ergio.ro\/co\/it\/wp-json\/wp\/v2\/media\/15509"}],"wp:attachment":[{"href":"https:\/\/www.ergio.ro\/co\/it\/wp-json\/wp\/v2\/media?parent=23004"}],"wp:term":[{"taxonomy":"jetpack-portfolio-type","embeddable":true,"href":"https:\/\/www.ergio.ro\/co\/it\/wp-json\/wp\/v2\/jetpack-portfolio-type?post=23004"},{"taxonomy":"jetpack-portfolio-tag","embeddable":true,"href":"https:\/\/www.ergio.ro\/co\/it\/wp-json\/wp\/v2\/jetpack-portfolio-tag?post=23004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}