{"id":23707,"date":"2023-07-17T10:23:53","date_gmt":"2023-07-17T08:23:53","guid":{"rendered":"https:\/\/www.ergio.ro\/co\/portfolio\/veronica\/"},"modified":"2023-07-17T10:23:53","modified_gmt":"2023-07-17T10:23:53","slug":"veronica","status":"publish","type":"jetpack-portfolio","link":"https:\/\/www.ergio.ro\/co\/fr\/portfolio\/veronica\/","title":{"rendered":"Veronica"},"content":{"rendered":"<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\">\n<div dir=\"auto\">\n<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\">\n<div dir=\"auto\">\n<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\">\n<div dir=\"auto\">Cette construction est une fusion extraordinaire de beaut\u00e9 architecturale et de confort moderne. Son charme intemporel, son savoir-faire impeccable et ses espaces de vie accueillants offrent une occasion unique d&rsquo;adopter un style de vie qui c\u00e9l\u00e8bre l&rsquo;\u00e9l\u00e9gance et la tranquillit\u00e9.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Nous discutons d&rsquo;une construction \u00e0 ossature bois de 201m2 \u00e0 Sabadell, Barcelone.<\/div>\n<div dir=\"auto\">La structure d&rsquo;ossature des murs ext\u00e9rieurs mesure 150x45mm, et elle est isol\u00e9e avec de la laine min\u00e9rale suivie de panneaux OSB de 12mm et d&rsquo;une membrane Rothoblaas pour contr\u00f4ler le passage de la vapeur d&rsquo;eau dans les structures en bois. Un c\u00f4t\u00e9 des murs ext\u00e9rieurs est fini avec une plaque de pl\u00e2tre de 12,5 mm et l&rsquo;autre avec du polystyr\u00e8ne et du pl\u00e2tre d\u00e9coratif.<\/div>\n<div dir=\"auto\">Les murs int\u00e9rieurs ont une structure d&rsquo;ossature mesurant 100x45mm, de la laine min\u00e9rale de verre &#8211; insonorisant, des plaques OSB de 12mm, des plaques de pl\u00e2tre et de la peinture blanche.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Ce projet est plus qu&rsquo;une simple maison; c&rsquo;est une passerelle vers un style de vie qui c\u00e9l\u00e8bre la vivacit\u00e9 et la joie de la culture espagnole. Ol\u00e9!<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<h6><\/h6>\n<h6>Surface<\/h6>\n<p>201m2<\/p>\n<h6><\/h6>\n<h6>Emplacement<\/h6>\n<p>Espagne<\/p>\n<h6><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Cette construction est une fusion extraordinaire de beaut\u00e9 architecturale et de confort moderne. Son charme intemporel, son savoir-faire impeccable et ses espaces de vie accueillants offrent une occasion unique d&rsquo;adopter un style de vie qui c\u00e9l\u00e8bre l&rsquo;\u00e9l\u00e9gance et la tranquillit\u00e9. Nous discutons d&rsquo;une construction \u00e0 ossature bois de 201m2 \u00e0 Sabadell, Barcelone. La structure d&rsquo;ossature [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31096,"comment_status":"open","ping_status":"closed","template":"","jetpack-portfolio-type":[151,152],"jetpack-portfolio-tag":[],"class_list":["post-23707","jetpack-portfolio","type-jetpack-portfolio","status-publish","has-post-thumbnail","hentry","jetpack-portfolio-type-ossature-bois","jetpack-portfolio-type-toit-plat"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ergio.ro\/co\/fr\/wp-json\/wp\/v2\/jetpack-portfolio\/23707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ergio.ro\/co\/fr\/wp-json\/wp\/v2\/jetpack-portfolio"}],"about":[{"href":"https:\/\/www.ergio.ro\/co\/fr\/wp-json\/wp\/v2\/types\/jetpack-portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.ergio.ro\/co\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ergio.ro\/co\/fr\/wp-json\/wp\/v2\/comments?post=23707"}],"version-history":[{"count":0,"href":"https:\/\/www.ergio.ro\/co\/fr\/wp-json\/wp\/v2\/jetpack-portfolio\/23707\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ergio.ro\/co\/fr\/wp-json\/wp\/v2\/media\/31096"}],"wp:attachment":[{"href":"https:\/\/www.ergio.ro\/co\/fr\/wp-json\/wp\/v2\/media?parent=23707"}],"wp:term":[{"taxonomy":"jetpack-portfolio-type","embeddable":true,"href":"https:\/\/www.ergio.ro\/co\/fr\/wp-json\/wp\/v2\/jetpack-portfolio-type?post=23707"},{"taxonomy":"jetpack-portfolio-tag","embeddable":true,"href":"https:\/\/www.ergio.ro\/co\/fr\/wp-json\/wp\/v2\/jetpack-portfolio-tag?post=23707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}